{"id":101309,"date":"2022-01-08T11:23:17","date_gmt":"2022-01-08T14:23:17","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=101309"},"modified":"2022-01-08T11:23:22","modified_gmt":"2022-01-08T14:23:22","slug":"hadson-nery-hadbala-estreia-perfil-onlyfans","status":"publish","type":"post","link":"https:\/\/www.portalpopmais.com.br\/en\/hadson-nery-hadbala-estreia-perfil-onlyfans\/","title":{"rendered":"Ex-BBB Hadson Nery estreia perfil no OnlyFans"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No in\u00edcio da semana, o ex-BBB20 <strong><a href=\"https:\/\/portalpopmais.com.br\/ex-bbb-hadson-sarrando-amigo\/\" target=\"_blank\" data-type=\"post\" data-id=\"88430\" rel=\"noreferrer noopener\">Hadson Nery<\/a><\/strong>, o <strong>Hadbala<\/strong>, comentou sobre abrir um perfil na plataforma de conte\u00fado adulto OnlyFans. <a href=\"http:\/\/instagram.com\/portalpopmais\" target=\"_blank\" rel=\"noopener\">Agora<\/a>, o ex-brother colocou o plano em a\u00e7\u00e3o e estreou neste s\u00e1bado (8) o perfil +18.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo ele, sua esposa est\u00e1 ciente e aprovou a venda de conte\u00fados exclusivos no site. <em>&#8220;Era um pedido de quase 60% do meu p\u00fablico das redes sociais, que eu aparecesse mais sensual. A galera [estava] sempre me pedindo fotos de sunga, coisa e tal, variados tipos de p\u00fablico e ent\u00e3o resolvi levar pra frente isso. Conversei com minha esposa entramos em comum acordo, para fazer algo que n\u00e3o atrapalhe nossas vidas, filhos e fam\u00edlia tamb\u00e9m&#8221;<\/em>, disse o ex-brother.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primeira foto do rapaz, inclusive, j\u00e1 saiu e voc\u00ea pode conferir abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Hadbala, o Hadson Nery do BBB20, entra pro mundo +18 e por apenas 200 reais por m\u00eas voc\u00ea pode ter acesso ao &quot;grand\u00e3o sem medo&quot;. Assinariam? <a href=\"https:\/\/t.co\/GCqBb3cF79\">pic.twitter.com\/GCqBb3cF79<\/a><\/p>&mdash; PAN (@forumpandlr) <a href=\"https:\/\/twitter.com\/forumpandlr\/status\/1479816500722741252?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 8, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pouco tempo ap\u00f3s sua passagem pelo Big Brother Brasil 20, uma suposta foto \u00edntima de Hadbala caiu nas redes sociais. Na \u00e9poca, o ex-jogador de futebol n\u00e3o comentou sobre o assunto. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio da semana, o ex-BBB20 Hadson Nery, o Hadbala, comentou sobre abrir um perfil na plataforma de conte\u00fado adulto OnlyFans. Agora, o ex-brother colocou o plano em a\u00e7\u00e3o e estreou neste s\u00e1bado (8) o perfil +18. Segundo ele, sua esposa est\u00e1 ciente e aprovou a venda de conte\u00fados exclusivos no site. &#8220;Era um pedido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":88431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[10336,8981],"class_list":["post-101309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-hadbala","tag-hadson-nery"],"_links":{"self":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/101309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=101309"}],"version-history":[{"count":0,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/101309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/88431"}],"wp:attachment":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=101309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=101309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=101309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}