{"id":191193,"date":"2023-09-13T09:30:00","date_gmt":"2023-09-13T12:30:00","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=191193"},"modified":"2023-09-13T08:22:45","modified_gmt":"2023-09-13T11:22:45","slug":"maira-cardi-afastamento-rede-social","status":"publish","type":"post","link":"https:\/\/www.portalpopmais.com.br\/en\/maira-cardi-afastamento-rede-social\/","title":{"rendered":"Ma\u00edra Cardi anuncia afastamento das redes sociais: &#8216;Ter mais tr\u00eas filhos&#8217;"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.portalpopmais.com.br\/en\/primo-rico-perdeu-23kg-para-casamento-com-maira-cardi-vergonha-na-cara\/\" data-type=\"post\" data-id=\"190196\">Ma\u00edra Cardi<\/a><\/strong> foi at\u00e9 as redes sociais nesta ter\u00e7a-feira (12) para anunciar que ir\u00e1 se afastar das redes sociais por tempo indeterminado. A decis\u00e3o vem na sequ\u00eancia do seu casamento com o <strong><a href=\"http:\/\/Twitter.com.br\/popmaisfm\" target=\"_blank\" rel=\"noopener\">Thiago Nigro<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Leia Mais: <\/strong><br><strong><a href=\"https:\/\/www.portalpopmais.com.br\/en\/sarah-aline-fim-relacionamento-ricardo-alface\/\">Sarah Aline fala sobre fim do relacionamento com Ricardo Alface: \u201cN\u00e3o existe\u201d<\/a><br><a href=\"https:\/\/www.portalpopmais.com.br\/en\/karol-conka-parceria-com-juliette\/\">Karol Conk\u00e1 fala sobre possibilidade de parceria com Juliette: \u201cMelhor momento\u201d<\/a><br><a href=\"https:\/\/www.portalpopmais.com.br\/en\/joabe-reis-lanca-se-eu-quiser-falar-com-deus\/\">Joabe Reis lan\u00e7a neo soul de \u201cSe eu quiser falar com Deus\u201d de Gil, em feat com Mirella Costa<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Estou aqui para dar um recado com dor no cora\u00e7\u00e3o e, ao mesmo tempo, com al\u00edvio. Vim para agradecer todos esses anos que temos passado juntos, desde a \u00e9poca do snapchat, quando n\u00e3o era Instagram. Voc\u00eas torceram pela minha felicidade, vibraram com as minhas conquistas. Sou quem sou e cheguei onde cheguei gra\u00e7as a voc\u00eas (&#8230;). Mas venho dizer para voc\u00eas que, pela primeira vez na minha vida, vou realmente desativar o meu Instagram de verdade, mas com o cora\u00e7\u00e3o em paz&#8221;,\u00a0come\u00e7ou ela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma\u00edra Cardi enfatizou que seu foco \u00e9 cuidar de sua sa\u00fade emocional e ter tr\u00eas filhos com o Primo Rico. Ela j\u00e1 \u00e9 m\u00e3e de Lucas Cardi e Sofia Aguiar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>f<\/mark>&#8220;Quero ter mais tr\u00eas filhos, e j\u00e1 n\u00e3o sou t\u00e3o novinha assim, o que requer mais aten\u00e7\u00e3o, mais cuidado, sa\u00fade emocional e f\u00edsica. Muita paz para que essas crian\u00e7as sejam geradas da melhor forma poss\u00edvel. Cuido muito da minha sa\u00fade. Eu quero fazer a pr\u00e9 concep\u00e7\u00e3o, o que significa que seis meses antes de conceber a crian\u00e7a, voc\u00ea muda drasticamente os seus h\u00e1bitos. O seu, e o do pai&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;H\u00e1 muito tempo que j\u00e1 n\u00e3o estou mais aqui porque preciso, mas sim porque gosto, quero e amo. Mas hoje me traz mais coisas negativas do que positivas, a internet virou terra de ningu\u00e9m. Para finalizar, quero me dedicar aos meus novos projetos de vida, escolhas, os meus filhos que j\u00e1 existem, e os que v\u00e3o existir. Quero tranquilidade para gerar de forma em paz. E quem sabe no final de tudo isso eu volte, ou n\u00e3o, quem sabe. Sou muito grata a tudo o que vivemos. Estou desativando, mas muito feliz com a minha escolha.&#8221;, finalizou Ma\u00edra Cardi.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ma\u00edra Cardi foi at\u00e9 as redes sociais nesta ter\u00e7a-feira (12) para anunciar que ir\u00e1 se afastar das redes sociais por tempo indeterminado. A decis\u00e3o vem na sequ\u00eancia do seu casamento com o Thiago Nigro. Leia Mais: Sarah Aline fala sobre fim do relacionamento com Ricardo Alface: \u201cN\u00e3o existe\u201dKarol Conk\u00e1 fala sobre possibilidade de parceria com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":186029,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[10355],"class_list":["post-191193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-maira-cardi"],"_links":{"self":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/191193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=191193"}],"version-history":[{"count":0,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/191193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/186029"}],"wp:attachment":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=191193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=191193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=191193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}