{"id":249080,"date":"2025-09-07T18:43:16","date_gmt":"2025-09-07T21:43:16","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=249080"},"modified":"2025-09-07T21:27:14","modified_gmt":"2025-09-08T00:27:14","slug":"confira-as-performances-do-vma-2025","status":"publish","type":"post","link":"https:\/\/www.portalpopmais.com.br\/en\/confira-as-performances-do-vma-2025\/","title":{"rendered":"Confira as performances do VMA 2025"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A noite deste domingo (7) foi cheia de surpresas no MTV Video Music Awards, com homenagens e performances que fizeram todo mundo vibrar. Artistas como Lady Gaga, Ricky Martin, Doja Cat, J Balvin e DJ Snake dominaram o palco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre hits que fizeram o p\u00fablico cantar junto e momentos especiais de homenagem, cada apresenta\u00e7\u00e3o trouxe sua pr\u00f3pria energia, reafirmando o talento e a import\u00e2ncia de cada artista na ind\u00fastria musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a cerim\u00f4nia teve estreias hist\u00f3ricas, como a primeira performance de Busta Rhymes no VMA e o tributo a Ozzy Osbourne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Confira quem se apresentou no VMA 2025:<\/strong> <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"2025 VMA Performances\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PLBPLVvU_jvGvS8V01wTC8X59mTNJNXtEk\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>A noite deste domingo (7) foi cheia de surpresas no MTV Video Music Awards, com homenagens e performances que fizeram todo mundo vibrar. Artistas como Lady Gaga, Ricky Martin, Doja Cat, J Balvin e DJ Snake dominaram o palco. Entre hits que fizeram o p\u00fablico cantar junto e momentos especiais de homenagem, cada apresenta\u00e7\u00e3o trouxe [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":244456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[18550,312,18171],"class_list":["post-249080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-destaque","tag-vma","tag-vma-2025"],"_links":{"self":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/249080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=249080"}],"version-history":[{"count":0,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/249080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/244456"}],"wp:attachment":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=249080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=249080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=249080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}