{"id":36026,"date":"2019-10-15T13:04:07","date_gmt":"2019-10-15T16:04:07","guid":{"rendered":"http:\/\/popmais.com.br\/?p=36026"},"modified":"2019-10-15T13:04:07","modified_gmt":"2019-10-15T16:04:07","slug":"bff-girls-contam-como-foi-participar-do-longa-o-melhor-verao-das-nossas-vidas","status":"publish","type":"post","link":"https:\/\/www.portalpopmais.com.br\/en\/bff-girls-contam-como-foi-participar-do-longa-o-melhor-verao-das-nossas-vidas\/","title":{"rendered":"BFF Girls contam como foi participar do longa O Melhor Ver\u00e3o das Nossas Vidas"},"content":{"rendered":"<p>A com\u00e9dia rom\u00e2ntica adolescente<em><strong>\u00a0O Melhor Ver\u00e3o das Nossas Vidas<\/strong>,\u00a0<\/em>produzida pela Moove House, est\u00e1 prevista para chegar aos cinemas no ver\u00e3o de 2020 e j\u00e1 teve suas grava\u00e7\u00f5es conclu\u00eddas. Protagonizado pelas <strong>BFF Girls<\/strong>, grupo formado pelas ex-participantes do <em>The Voice Kids<\/em>, <strong>Bia Torres,<\/strong> <strong>Giulia Nassa<\/strong> e <strong>Laura Castro,<\/strong> o filme conta a hist\u00f3ria de tr\u00eas amigas que t\u00eam o sonho de alcan\u00e7ar o estrelato no mundo da m\u00fasica.<\/p>\n<p>Ao falarem sobre como foi participar da produ\u00e7\u00e3o, as meninas se mostraram muito realizadas. \u201cSou eternamente grata por tudo que esses \u00faltimos meses me proporcionaram. Ri muito, chorei, me apaixonei, evolui, sorri, errei, vivi! Tenho certeza que todos n\u00f3s vamos lembrar pra sempre desses momentos \u00fanicos e m\u00e1gicos\u201d, conta Giulia.<\/p>\n<p>Para Laura, participar do filme tamb\u00e9m foi uma experi\u00eancia surpreendente. \u201cMinhas expectativas foram completamente superadas quando come\u00e7amos a gravar. Do per\u00edodo de prepara\u00e7\u00e3o para o filme, e at\u00e9 hoje, ainda me sinto extasiada do tanto que foi precioso fazer parte de um projeto como esse. Eu aprendi demais com todas as pessoas que estavam l\u00e1 e me diverti como se eu estivesse de f\u00e9rias, algo que me encheu de gratid\u00e3o!\u201d.<\/p>\n<div id=\"attachment_36028\" style=\"width: 877px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36028\" class=\"size-full wp-image-36028\" src=\"http:\/\/popmais.com.br\/wp-content\/uploads\/2019\/10\/OMV_SerendipityInc_ODD01_LC_00002.jpg\" alt=\"\" width=\"867\" height=\"1300\" title=\"\"><p id=\"caption-attachment-36028\" class=\"wp-caption-text\">Cena do filme &#8220;O Melhor Ver\u00e3o das Nossas Vidas&#8221; (Foto: Divulga\u00e7\u00e3o)<\/p><\/div>\n<p>\u201cForam dias muito intensos, com muita dedica\u00e7\u00e3o e esfor\u00e7o por parte de todos, mas acima de tudo foram uns dos melhores dias da minha vida. N\u00e3o cans\u00e1vamos, quer\u00edamos estar filmando o tempo inteiro porque amamos fazer aquilo e est\u00e1vamos do lado de pessoas maravilhosas\u201d, relembra Bia.<\/p>\n<p>As protagonistas tamb\u00e9m n\u00e3o veem a hora de assistir ao longa, e est\u00e3o com expectativas bem altas. \u201cS\u00f3 quero ver o resultado final, j\u00e1 estou me preparando emocionalmente para o tanto que vou chorar quando nos assistir no cinema\u201d, revela Bia.<\/p>\n<p>Para Laura, \u00e9 certeza que o resultado ser\u00e1 incr\u00edvel, \u201ctodos n\u00f3s, equipe e elenco, demos nosso melhor\u201d. Ela ainda espera que quem assistir se divirta com a hist\u00f3ria e se contagie com a energia solar do filme, \u201dque reflete a energia das pessoas com as quais tive a honra de trabalhar!\u201d, continua.<\/p>\n<p>Giulia acredita que todo mundo vai rir muito, cantar alto, e se identificar com as personagens. \u201cAgora \u00e9 s\u00f3 segurar a ansiedade e a saudade que j\u00e1 bateu de ficar longe da galera! Muito feliz de poder reencontrar todo mundo em Janeiro e dessa vez junto com o p\u00fablico\u201d, finaliza Giulia.<\/p>\n<p>Al\u00e9m das BFF Girls, tamb\u00e9m fazem parte do n\u00facleo jovem do longa, Giovanna Chaves, Enrico Lima, Murilo Bispo, e Bela Fernandes. O elenco re\u00fane ainda Maur\u00edcio Meirelles, M\u00e1rvio L\u00facio (Carioca), Jo\u00e3o Quirino, Rafael Zulu, Gisele Prattes, Daniel Erthal, Carlos Bonow e Laura Proen\u00e7a. O respons\u00e1vel pela dire\u00e7\u00e3o do filme \u00e9 Adolpho Knauth, da produtora Moove House, e o roteiro \u00e9 de Cadu Pereiva.<\/p>\n<p><strong><em>O Melhor Ver\u00e3o das Nossas Vidas<\/em><\/strong>\u00a0tem apoio da Secretaria de Turismo do Estado de S\u00e3o Paulo e ser\u00e1 lan\u00e7ado pela Galeria Distribuidora, que tamb\u00e9m \u00e9 coprodutora. A produ\u00e7\u00e3o \u00e9 da Moove House e o projeto ainda conta com a parceira da Sony Music.<\/p>\n<h3><strong>Sinopse<\/strong><\/h3>\n<p>Bia, Giulia e Laura conseguem uma grande chance de participar de um Festival de M\u00fasica muito famoso no Guaruj\u00e1. S\u00f3 que todos os planos dessas tr\u00eas amigas v\u00e3o por \u00e1gua abaixo quando elas descobrem que ficaram de recupera\u00e7\u00e3o na escola. Assim elas ter\u00e3o uma miss\u00e3o arriscad\u00edssima pela frente: irem ao Festival sem que seus pais fiquem sabendo.<\/p>\n<p>Para conseguir ir atr\u00e1s dos seus sonhos elas pedir\u00e3o ajuda para J\u00falio (Enrico Lima), o menino mais nerd da sala. Mas, para aceitar esta proposta, o garoto imp\u00f5e uma condi\u00e7\u00e3o: as tr\u00eas amigas ter\u00e3o que ajud\u00e1-lo a conquistar o cora\u00e7\u00e3o da garota mais arrogante e chata do col\u00e9gio, a Hel\u00f4 Diniz (Giovanna Chaves). Na praia conhecer\u00e3o Th\u00e9o (Murilo Bispo) um jovem m\u00fasico gente boa e sua irm\u00e3 surda Carol (Bela Fernandes).<\/p>\n<p>Esses adolescentes viver\u00e3o muitas aventuras para alcan\u00e7arem os seus objetivos, e com muita m\u00fasica ter\u00e3o um intenso ver\u00e3o pela frente, que ficar\u00e1 guardado em suas mem\u00f3rias para sempre!<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Sobre a Moove House<\/u><\/strong><\/p>\n<p>Criada em 2012, a Moove House tem como foco o desenvolvimento e produ\u00e7\u00e3o de conte\u00fado audiovisual, destacando-se pela qualidade de suas realiza\u00e7\u00f5es e criatividade. Atualmente a produtora, que \u00e9 comandada pelos s\u00f3cios Adolpho Knauth e Denis Knauth, possui uma base de produ\u00e7\u00e3o no Rio de Janeiro e conta com uma estrutura otimizada e competente nos departamentos de cria\u00e7\u00e3o de conte\u00fado, produ\u00e7\u00e3o, dire\u00e7\u00e3o, edi\u00e7\u00e3o e anima\u00e7\u00e3o. Inicialmente a empresa era focada em publicidade, e realizou campanhas de sucesso com marcas como Coca-Cola Brasil, Red Bull, L\u2019Oreal, entre outras. A partir de 2018, com um novo posicionamento no mercado, come\u00e7ou a sua atua\u00e7\u00e3o exclusiva na produ\u00e7\u00e3o de anima\u00e7\u00f5es, videoclipes, s\u00e9ries e longas metragens. No ramo do entretenimento fez diversos projetos, entre eles os document\u00e1rios \u201cJ\u00e1 Ouvi Falar\u201d, que conta a trajet\u00f3ria da banda Playmobille, e \u201cO Lado de C\u00e1\u201d, sobre ressocializa\u00e7\u00e3o e sistema carcer\u00e1rio brasileiro, a s\u00e9rie de fic\u00e7\u00e3o \u201cLike Lika\u201d, que foi vencedora do pr\u00eamio The Best Web &amp; TV Series pelo Brazil International Film Festival; a anima\u00e7\u00e3o \u201cA Nova Turma do Bal\u00e3o M\u00e1gico\u201d e a anima\u00e7\u00e3o infantil \u201cD\u00f3-R\u00e9 Mundo\u201d<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>A com\u00e9dia rom\u00e2ntica adolescente\u00a0O Melhor Ver\u00e3o das Nossas Vidas,\u00a0produzida pela Moove House, est\u00e1 prevista para chegar aos cinemas no ver\u00e3o de 2020 e j\u00e1 teve suas grava\u00e7\u00f5es conclu\u00eddas. Protagonizado pelas BFF Girls, grupo formado pelas ex-participantes do The Voice Kids, Bia Torres, Giulia Nassa e Laura Castro, o filme conta a hist\u00f3ria de tr\u00eas amigas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[503,696,7182],"class_list":["post-36026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filmes-series","tag-bff","tag-bff-girls","tag-o-melhor-verao-das-nossas-vidas"],"_links":{"self":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/36026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=36026"}],"version-history":[{"count":0,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/36026\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=36026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=36026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=36026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}